{"id":1100084625,"date":"2025-03-04T15:41:44","date_gmt":"2025-03-04T14:41:44","guid":{"rendered":"https:\/\/www.group-indigo.com\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/"},"modified":"2025-07-04T11:14:12","modified_gmt":"2025-07-04T09:14:12","slug":"aparcamiento-de-la-estacion-saint-jean-belcier","status":"publish","type":"reference","link":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/","title":{"rendered":"Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier"},"content":{"rendered":"\n<section class=\"gut-block gut-hero-simple type-image\" >\n\t<div class=\"bg\">\n\t\t<div class=\"wrap\"><\/div>\n\t<\/div>\n\n\t<div class=\"wrap\">\n\t\t\t\t\t<div class=\"grid-container\">\n\t\t\t\t<div class=\"grid-el-md-5 contents\">\n\t\t\t\t\t\n<nav class=\"breadcrumb\" role=\"navigation\" aria-label=\"Rastro de migas de pan :\">\n\t<ul class=\"breadcrumb-list\">\n\t\t\t\t\t\t\t\t\t<li class=\"breadcrumb-item\" >\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.group-indigo.com\/es\/\">Inicio<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li class=\"breadcrumb-item\" >\n\t\t\t\t\t\t\t\t\t\t\tActividades\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li class=\"breadcrumb-item\" >\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.group-indigo.com\/es\/referencias\/\">Referencias<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<li class=\"breadcrumb-item\" aria-current=\"page\">\n\t\t\t\t\t\t\t\t\t\t\tAparcamiento de la estaci\u00f3n Saint-Jean-Belcier\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n<\/nav>\n\n\n\t\t\t\t\t<div class=\"content-part\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"reference-infos\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"localisation\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tBurdeos, \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tFrancia\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t&#8211;\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>Estaciones<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h1 class=\"block-title titre-h2\">Aparcamiento de la estaci\u00f3n de Saint-Jean-Belcier &#8211; Burdeos<\/h1>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"textes\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"texte wysiwyg-content\">\n\t\t\t\t\t\t\t\t\t<p>Un aparcamiento perfectamente integrado en el proyecto global de desarrollo de la estaci\u00f3n.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<div class=\"img-part grid-el-md-6\">\n\t\t\t\t\t\t<figure class=\"img\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1295\" height=\"926\" src=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux.png\" class=\"attachment-banner size-banner\" alt=\"\" srcset=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux.png 1295w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux-300x215.png 300w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux-1024x732.png 1024w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux-768x549.png 768w\" sizes=\"(max-width: 1295px) 100vw, 1295px\" \/>\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t<\/div>\n<\/section>\r\n\n\n\t<section class=\"gut-block gut-chiffres-cles bg-color-blanc\" >\n\t\t<div class=\"wrap\">\n\t\t\t<div class=\"chiffres-cles\">\n\t\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"chiffre\">1.600<\/p>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description\">plazas de aparcamiento<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"chiffre\">2 <\/p>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"description\">aparcamientos<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t<\/section>\n\r\n\n\n<section class=\"gut-block gut-texte bg-color-blanc\" >\n\t<div class=\"wrap\">\n\t\t<div class=\"texte wysiwyg-content\">\n\t\t\t<p>El aparcamiento Gare Saint-Jean-Belcier P3 es un aparcamiento de superestructura financiado y explotado por INDIGO. Se construy\u00f3 a lo largo de dos a\u00f1os en el marco de la metamorfosis de la estaci\u00f3n Saint-Jean para acoger la llegada de la l\u00ednea de alta velocidad. <\/p>\n<p>Como puerta de entrada a una estaci\u00f3n modernizada, el aparcamiento P3 se ha dise\u00f1ado para ofrecer a los viajeros un estacionamiento moderno, de f\u00e1cil acceso y adaptado a los retos que plantea el n\u00famero de viajeros. Est\u00e1 equipado con instalaciones y servicios dise\u00f1ados para facilitar la experiencia del cliente (gu\u00eda de aparcamiento, disponibilidad de plazas en tiempo real y equipos de peaje de \u00faltima generaci\u00f3n que permiten una amplia gama de m\u00e9todos de pago (CB, NFC, tarjeta GR, distintivo Liber-T, etc.). <\/p>\n<p>La arquitectura elegida para este aparcamiento es el resultado de un complejo desaf\u00edo t\u00e9cnico, caracterizado por una estructura de hormig\u00f3n lo m\u00e1s esbelta posible. Esta arquitectura particularmente a\u00e9rea se integra perfectamente en su entorno ferroviario. <\/p>\n<p><strong>Una oferta de aparcamiento adaptada a todos los usuarios<\/strong><\/p>\n<p>Con 6 niveles elevados servidos por una rampa circular central de acceso r\u00e1pido a las plantas superiores, el aparcamiento P3 dispone de zonas reservadas para personas con movilidad reducida, veh\u00edculos de dos ruedas motorizados y veh\u00edculos el\u00e9ctricos (zonas equipadas con estaciones de recarga).<br \/>\nEl nivel -1 est\u00e1 dedicado a la zona de bajada (70 plazas con aparcamiento gratuito de 10 minutos) y a una zona premium con unas cuarenta plazas disponibles s\u00f3lo con reserva.<\/p>\n<p>Un segundo aparcamiento (P4), con capacidad para otras 750 plazas, completa la oferta de aparcamiento.<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/section>\r\n\n\n<section class=\"gut-block gut-slider-images bg-color-blanc\" >\n\t<div class=\"wrap\">\n\t\t\n\t\t<div class=\"slider-container\">\n\t\t\t<div class=\"swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-110-1-1620x1080.jpg\" class=\"img-container\" >\n\t\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<div class=\"img\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-110-1-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-110-1-1024x683.jpg 1024w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-110-1-300x200.jpg 300w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-110-1-768x512.jpg 768w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-110-1-1536x1024.jpg 1536w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-110-1-scaled.jpg 2048w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-110-1-1620x1080.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-095-1-1620x1080.jpg\" class=\"img-container\" >\n\t\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<div class=\"img\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-095-1-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-095-1-1024x683.jpg 1024w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-095-1-300x200.jpg 300w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-095-1-768x512.jpg 768w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-095-1-1536x1024.jpg 1536w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-095-1-scaled.jpg 2048w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-095-1-1620x1080.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-051-1620x1080.jpg\" class=\"img-container\" >\n\t\t\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t<div class=\"img\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-051-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-051-1024x683.jpg 1024w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-051-300x200.jpg 300w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-051-768x512.jpg 768w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-051-1536x1024.jpg 1536w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-051-scaled.jpg 2048w, https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/03\/Bordeaux-051-1620x1080.jpg 1620w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"swiper-nav\">\n\t\t\t\t<button type=\"button\" class=\"swiper-btn swiper-btn-prev\" aria-label=\"Anterior\"><span class=\"icon icon-arrow-left\" aria-hidden=\"true\"><\/span><\/button>\n\t\t\t\t<button type=\"button\" class=\"swiper-btn swiper-btn-next\" aria-label=\"Siguiente\"><span class=\"icon icon-arrow-right\" aria-hidden=\"true\"><\/span><\/button>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>","protected":false},"featured_media":1100028039,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1100084625","reference","type-reference","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier - Groupe INDIGO<\/title>\n<meta name=\"description\" content=\"El aparcamiento P3 Gare Saint-Jean-Belcier es un aparcamiento de superestructura financiado y explotado por INDIGO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier - Groupe INDIGO\" \/>\n<meta property=\"og:description\" content=\"El aparcamiento P3 Gare Saint-Jean-Belcier es un aparcamiento de superestructura financiado y explotado por INDIGO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe INDIGO\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T09:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1295\" \/>\n\t<meta property=\"og:image:height\" content=\"926\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/reference\\\/aparcamiento-de-la-estacion-saint-jean-belcier\\\/\",\"url\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/reference\\\/aparcamiento-de-la-estacion-saint-jean-belcier\\\/\",\"name\":\"Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier - Groupe INDIGO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/reference\\\/aparcamiento-de-la-estacion-saint-jean-belcier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/reference\\\/aparcamiento-de-la-estacion-saint-jean-belcier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.group-indigo.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/gare-de-bordeaux.png\",\"datePublished\":\"2025-03-04T14:41:44+00:00\",\"dateModified\":\"2025-07-04T09:14:12+00:00\",\"description\":\"El aparcamiento P3 Gare Saint-Jean-Belcier es un aparcamiento de superestructura financiado y explotado por INDIGO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/reference\\\/aparcamiento-de-la-estacion-saint-jean-belcier\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/reference\\\/aparcamiento-de-la-estacion-saint-jean-belcier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/reference\\\/aparcamiento-de-la-estacion-saint-jean-belcier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.group-indigo.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/gare-de-bordeaux.png\",\"contentUrl\":\"https:\\\/\\\/www.group-indigo.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/gare-de-bordeaux.png\",\"width\":1295,\"height\":926},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/reference\\\/aparcamiento-de-la-estacion-saint-jean-belcier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/\",\"name\":\"Groupe INDIGO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/#organization\",\"name\":\"Groupe INDIGO\",\"url\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.group-indigo.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/login-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.group-indigo.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/login-logo.svg\",\"width\":223,\"height\":49,\"caption\":\"Groupe INDIGO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.group-indigo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier - Groupe INDIGO","description":"El aparcamiento P3 Gare Saint-Jean-Belcier es un aparcamiento de superestructura financiado y explotado por INDIGO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/","og_locale":"es_ES","og_type":"article","og_title":"Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier - Groupe INDIGO","og_description":"El aparcamiento P3 Gare Saint-Jean-Belcier es un aparcamiento de superestructura financiado y explotado por INDIGO.","og_url":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/","og_site_name":"Groupe INDIGO","article_modified_time":"2025-07-04T09:14:12+00:00","og_image":[{"width":1295,"height":926,"url":"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/","url":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/","name":"Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier - Groupe INDIGO","isPartOf":{"@id":"https:\/\/www.group-indigo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/#primaryimage"},"image":{"@id":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux.png","datePublished":"2025-03-04T14:41:44+00:00","dateModified":"2025-07-04T09:14:12+00:00","description":"El aparcamiento P3 Gare Saint-Jean-Belcier es un aparcamiento de superestructura financiado y explotado por INDIGO.","breadcrumb":{"@id":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/#primaryimage","url":"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux.png","contentUrl":"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2025\/02\/gare-de-bordeaux.png","width":1295,"height":926},{"@type":"BreadcrumbList","@id":"https:\/\/www.group-indigo.com\/es\/reference\/aparcamiento-de-la-estacion-saint-jean-belcier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.group-indigo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aparcamiento de la estaci\u00f3n Saint-Jean-Belcier"}]},{"@type":"WebSite","@id":"https:\/\/www.group-indigo.com\/es\/#website","url":"https:\/\/www.group-indigo.com\/es\/","name":"Groupe INDIGO","description":"","publisher":{"@id":"https:\/\/www.group-indigo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.group-indigo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.group-indigo.com\/es\/#organization","name":"Groupe INDIGO","url":"https:\/\/www.group-indigo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.group-indigo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2026\/03\/login-logo.svg","contentUrl":"https:\/\/www.group-indigo.com\/wp-content\/uploads\/2026\/03\/login-logo.svg","width":223,"height":49,"caption":"Groupe INDIGO"},"image":{"@id":"https:\/\/www.group-indigo.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.group-indigo.com\/es\/wp-json\/wp\/v2\/reference\/1100084625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.group-indigo.com\/es\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/www.group-indigo.com\/es\/wp-json\/wp\/v2\/types\/reference"}],"version-history":[{"count":2,"href":"https:\/\/www.group-indigo.com\/es\/wp-json\/wp\/v2\/reference\/1100084625\/revisions"}],"predecessor-version":[{"id":1100091833,"href":"https:\/\/www.group-indigo.com\/es\/wp-json\/wp\/v2\/reference\/1100084625\/revisions\/1100091833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.group-indigo.com\/es\/wp-json\/wp\/v2\/media\/1100028039"}],"wp:attachment":[{"href":"https:\/\/www.group-indigo.com\/es\/wp-json\/wp\/v2\/media?parent=1100084625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}